{"id":90,"date":"2016-06-20T22:52:55","date_gmt":"2016-06-20T20:52:55","guid":{"rendered":"https:\/\/riviera2016.phisites.nl\/?p=90"},"modified":"2017-04-24T09:16:32","modified_gmt":"2017-04-24T07:16:32","slug":"23-zonnige-dag-op-de-camping-le-fonti","status":"publish","type":"post","link":"https:\/\/riviera2016.phisites.nl\/index.php\/2016\/06\/20\/23-zonnige-dag-op-de-camping-le-fonti\/","title":{"rendered":"23 &#8211; Zonnige dag op de camping Le Fonti"},"content":{"rendered":"<p>Zonnige dag camping is bijna leeggelopen. De nodige huishoudelijke klusjes gedaan. Annelies heeft weer voor kapster gespeeld en nu loop ik er weer gesoigneerd bij. Veel gelezen om vijf uur een duik in het zwembad en baantjes zwemmen. Eerst kopje koffie drinken en boek lezen daarna om zeven uur eten gaan klaarmaken. Op Italiaanse tijd gegeten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zonnige dag camping is bijna leeggelopen. De nodige huishoudelijke klusjes gedaan. Annelies heeft weer voor kapster gespeeld en nu loop ik er weer gesoigneerd bij. Veel gelezen om vijf uur een duik in het zwembad en baantjes zwemmen. Eerst kopje koffie drinken en boek lezen daarna om zeven uur eten gaan klaarmaken. Op Italiaanse tijd &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/riviera2016.phisites.nl\/index.php\/2016\/06\/20\/23-zonnige-dag-op-de-camping-le-fonti\/\" class=\"more-link\">Lees verder <span class=\"screen-reader-text\">&#8220;23 &#8211; Zonnige dag op de camping Le Fonti&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,40],"tags":[],"class_list":["post-90","post","type-post","status-publish","format-standard","hentry","category-dag23","category-dagboek"],"_links":{"self":[{"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/posts\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":1,"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/posts\/90\/revisions"}],"predecessor-version":[{"id":91,"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/posts\/90\/revisions\/91"}],"wp:attachment":[{"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/categories?post=90"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riviera2016.phisites.nl\/index.php\/wp-json\/wp\/v2\/tags?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}